{"id":1104,"date":"2016-01-20T16:33:52","date_gmt":"2016-01-20T15:33:52","guid":{"rendered":"http:\/\/paartherapie-coupletherapy.de\/en\/?p=1104"},"modified":"2016-01-20T16:38:08","modified_gmt":"2016-01-20T15:38:08","slug":"workshops-in-krakau-2","status":"publish","type":"post","link":"https:\/\/paartherapie-coupletherapy.de\/en\/workshops-in-krakau-2\/","title":{"rendered":"Workshops in Krakau"},"content":{"rendered":"<h1>Workshops in Krakau<\/h1>\n<p>Zweimal wurde ich im vergangenen Jahr nach Krakau eingeladen, um dort mit den\u00a0 Kollegen zu arbeiten. Der Austausch mit den polnischen Psychiatern und Psychologen war ausgesprochen herzlich und interessant.<\/p>\n<p>Bei meinem ersten workshop habe ich mit den Kollegen \u00fcber das Thema <strong>Qualit\u00e4t\u00a0 in der Psychotherapie<\/strong> im Allgemeinen diskutiert, der zweite workshop hatte den Schwerpunkt \u201e<strong>Paartherapie<\/strong>\u201c. Besonders das Vorgehen bei \u201e<strong>Discernment Counselling<\/strong>\u201c, also Begleitung von Paaren, bei denen ein Partner die Beziehung beenden will und der andere nicht, hat gro\u00dfes Interesse geweckt. Meine Erfahrung in der Arbeit mit diesen Paaren, ist, dass Beratung und Entscheidungsfindung nur Sinn macht, wenn sie in getrennten Einzelgespr\u00e4chen erfolgt.<\/p>\n<p>Gute, anregende Diskussionen und Kontakte in meiner Lieblingsstadt, ich war begeistert!<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Workshops in Krakau Zweimal wurde ich im vergangenen Jahr nach Krakau eingeladen, um dort mit den\u00a0 Kollegen zu arbeiten. Der Austausch mit den polnischen Psychiatern und<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":2,"featured_media":1067,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-1104","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Workshops in Krakau - Praxis f\u00fcr Paartherapie Berlin-Mitte<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/paartherapie-coupletherapy.de\/workshops-in-krakau-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Workshops in Krakau - Praxis f\u00fcr Paartherapie Berlin-Mitte\" \/>\n<meta property=\"og:description\" content=\"Workshops in Krakau Zweimal wurde ich im vergangenen Jahr nach Krakau eingeladen, um dort mit den\u00a0 Kollegen zu arbeiten. Der Austausch mit den polnischen Psychiatern und [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/paartherapie-coupletherapy.de\/workshops-in-krakau-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Praxis f\u00fcr Paartherapie Berlin-Mitte\" \/>\n<meta property=\"article:published_time\" content=\"2016-01-20T15:33:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-01-20T15:38:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/paartherapie-coupletherapy.de\/wp-content\/uploads\/2016\/01\/krakau-paartherapie.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"233\" \/>\n\t<meta property=\"og:image:height\" content=\"350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Julia Bellabarba\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Julia Bellabarba\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/paartherapie-coupletherapy.de\/workshops-in-krakau-2\/\",\"url\":\"https:\/\/paartherapie-coupletherapy.de\/workshops-in-krakau-2\/\",\"name\":\"Workshops in Krakau - Praxis f\u00fcr Paartherapie Berlin-Mitte\",\"isPartOf\":{\"@id\":\"https:\/\/paartherapie-coupletherapy.de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/paartherapie-coupletherapy.de\/workshops-in-krakau-2\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/paartherapie-coupletherapy.de\/workshops-in-krakau-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/paartherapie-coupletherapy.de\/wp-content\/uploads\/2016\/01\/krakau-paartherapie.jpg\",\"datePublished\":\"2016-01-20T15:33:52+00:00\",\"dateModified\":\"2016-01-20T15:38:08+00:00\",\"author\":{\"@id\":\"https:\/\/paartherapie-coupletherapy.de\/#\/schema\/person\/feaec33cc2479c53caf5cfeffd4bccb0\"},\"breadcrumb\":{\"@id\":\"https:\/\/paartherapie-coupletherapy.de\/workshops-in-krakau-2\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/paartherapie-coupletherapy.de\/workshops-in-krakau-2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/paartherapie-coupletherapy.de\/workshops-in-krakau-2\/#primaryimage\",\"url\":\"https:\/\/paartherapie-coupletherapy.de\/wp-content\/uploads\/2016\/01\/krakau-paartherapie.jpg\",\"contentUrl\":\"https:\/\/paartherapie-coupletherapy.de\/wp-content\/uploads\/2016\/01\/krakau-paartherapie.jpg\",\"width\":233,\"height\":350},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/paartherapie-coupletherapy.de\/workshops-in-krakau-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/paartherapie-coupletherapy.de\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Workshops in Krakau\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/paartherapie-coupletherapy.de\/#website\",\"url\":\"https:\/\/paartherapie-coupletherapy.de\/\",\"name\":\"Praxis f\u00fcr Paartherapie Berlin-Mitte\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/paartherapie-coupletherapy.de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/paartherapie-coupletherapy.de\/#\/schema\/person\/feaec33cc2479c53caf5cfeffd4bccb0\",\"name\":\"Julia Bellabarba\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/paartherapie-coupletherapy.de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/230c5f20075f1ee23ffc6ecb25586d834a8076bcbc3def1274d5c0ce41d3f8f7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/230c5f20075f1ee23ffc6ecb25586d834a8076bcbc3def1274d5c0ce41d3f8f7?s=96&d=mm&r=g\",\"caption\":\"Julia Bellabarba\"},\"url\":\"https:\/\/paartherapie-coupletherapy.de\/en\/author\/jbella\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Workshops in Krakau - Praxis f\u00fcr Paartherapie Berlin-Mitte","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/paartherapie-coupletherapy.de\/workshops-in-krakau-2\/","og_locale":"en_US","og_type":"article","og_title":"Workshops in Krakau - Praxis f\u00fcr Paartherapie Berlin-Mitte","og_description":"Workshops in Krakau Zweimal wurde ich im vergangenen Jahr nach Krakau eingeladen, um dort mit den\u00a0 Kollegen zu arbeiten. Der Austausch mit den polnischen Psychiatern und [\u2026]","og_url":"https:\/\/paartherapie-coupletherapy.de\/workshops-in-krakau-2\/","og_site_name":"Praxis f\u00fcr Paartherapie Berlin-Mitte","article_published_time":"2016-01-20T15:33:52+00:00","article_modified_time":"2016-01-20T15:38:08+00:00","og_image":[{"width":233,"height":350,"url":"https:\/\/paartherapie-coupletherapy.de\/wp-content\/uploads\/2016\/01\/krakau-paartherapie.jpg","type":"image\/jpeg"}],"author":"Julia Bellabarba","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Julia Bellabarba","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/paartherapie-coupletherapy.de\/workshops-in-krakau-2\/","url":"https:\/\/paartherapie-coupletherapy.de\/workshops-in-krakau-2\/","name":"Workshops in Krakau - Praxis f\u00fcr Paartherapie Berlin-Mitte","isPartOf":{"@id":"https:\/\/paartherapie-coupletherapy.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/paartherapie-coupletherapy.de\/workshops-in-krakau-2\/#primaryimage"},"image":{"@id":"https:\/\/paartherapie-coupletherapy.de\/workshops-in-krakau-2\/#primaryimage"},"thumbnailUrl":"https:\/\/paartherapie-coupletherapy.de\/wp-content\/uploads\/2016\/01\/krakau-paartherapie.jpg","datePublished":"2016-01-20T15:33:52+00:00","dateModified":"2016-01-20T15:38:08+00:00","author":{"@id":"https:\/\/paartherapie-coupletherapy.de\/#\/schema\/person\/feaec33cc2479c53caf5cfeffd4bccb0"},"breadcrumb":{"@id":"https:\/\/paartherapie-coupletherapy.de\/workshops-in-krakau-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/paartherapie-coupletherapy.de\/workshops-in-krakau-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/paartherapie-coupletherapy.de\/workshops-in-krakau-2\/#primaryimage","url":"https:\/\/paartherapie-coupletherapy.de\/wp-content\/uploads\/2016\/01\/krakau-paartherapie.jpg","contentUrl":"https:\/\/paartherapie-coupletherapy.de\/wp-content\/uploads\/2016\/01\/krakau-paartherapie.jpg","width":233,"height":350},{"@type":"BreadcrumbList","@id":"https:\/\/paartherapie-coupletherapy.de\/workshops-in-krakau-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/paartherapie-coupletherapy.de\/en\/"},{"@type":"ListItem","position":2,"name":"Workshops in Krakau"}]},{"@type":"WebSite","@id":"https:\/\/paartherapie-coupletherapy.de\/#website","url":"https:\/\/paartherapie-coupletherapy.de\/","name":"Praxis f\u00fcr Paartherapie Berlin-Mitte","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/paartherapie-coupletherapy.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/paartherapie-coupletherapy.de\/#\/schema\/person\/feaec33cc2479c53caf5cfeffd4bccb0","name":"Julia Bellabarba","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/paartherapie-coupletherapy.de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/230c5f20075f1ee23ffc6ecb25586d834a8076bcbc3def1274d5c0ce41d3f8f7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/230c5f20075f1ee23ffc6ecb25586d834a8076bcbc3def1274d5c0ce41d3f8f7?s=96&d=mm&r=g","caption":"Julia Bellabarba"},"url":"https:\/\/paartherapie-coupletherapy.de\/en\/author\/jbella\/"}]}},"_links":{"self":[{"href":"https:\/\/paartherapie-coupletherapy.de\/en\/wp-json\/wp\/v2\/posts\/1104","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/paartherapie-coupletherapy.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/paartherapie-coupletherapy.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/paartherapie-coupletherapy.de\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/paartherapie-coupletherapy.de\/en\/wp-json\/wp\/v2\/comments?post=1104"}],"version-history":[{"count":1,"href":"https:\/\/paartherapie-coupletherapy.de\/en\/wp-json\/wp\/v2\/posts\/1104\/revisions"}],"predecessor-version":[{"id":1105,"href":"https:\/\/paartherapie-coupletherapy.de\/en\/wp-json\/wp\/v2\/posts\/1104\/revisions\/1105"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/paartherapie-coupletherapy.de\/en\/wp-json\/wp\/v2\/media\/1067"}],"wp:attachment":[{"href":"https:\/\/paartherapie-coupletherapy.de\/en\/wp-json\/wp\/v2\/media?parent=1104"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/paartherapie-coupletherapy.de\/en\/wp-json\/wp\/v2\/categories?post=1104"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/paartherapie-coupletherapy.de\/en\/wp-json\/wp\/v2\/tags?post=1104"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}