{"id":1411,"date":"2017-07-18T12:48:57","date_gmt":"2017-07-18T10:48:57","guid":{"rendered":"http:\/\/paartherapie-coupletherapy.de\/en\/interview-zum-thema-scheidung-viele-wollen-noch-etwas-retten\/"},"modified":"2018-09-07T13:17:30","modified_gmt":"2018-09-07T11:17:30","slug":"interview-zum-thema-scheidung-viele-wollen-noch-etwas-retten","status":"publish","type":"post","link":"https:\/\/paartherapie-coupletherapy.de\/en\/interview-zum-thema-scheidung-viele-wollen-noch-etwas-retten\/","title":{"rendered":"Interview zum Thema Scheidung: Viele wollen noch etwas retten"},"content":{"rendered":"<h1>Die Scheidungszahlen sinken?<\/h1>\n<p>Ein Interview, das Frau Wettlaufer-Pohl von der Nordhessischen Allgemeinen, mit mir gef\u00fchrt hat, hier zum Nachlesen: <a href=\"https:\/\/paartherapie-coupletherapy.de\/wp-content\/uploads\/2017\/07\/20170717-Interview-sinkende-Scheidungszahlen.pdf\">20170717- Interview-sinkende-Scheidungszahlen<\/a> (PDF)<\/p>\n<h1><\/h1>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Scheidungszahlen sinken? Ein Interview, das Frau Wettlaufer-Pohl von der Nordhessischen Allgemeinen, mit mir gef\u00fchrt hat, hier zum Nachlesen: 20170717- Interview-sinkende-Scheidungszahlen (PDF) &nbsp; &nbsp;<\/p>\n","protected":false},"author":1,"featured_media":1587,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-1411","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-im-gespraech-en"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Interview zum Thema Scheidung: Viele wollen noch etwas retten - Praxis f\u00fcr Paartherapie Berlin-Mitte<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/paartherapie-coupletherapy.de\/interview-zum-thema-scheidung-viele-wollen-noch-etwas-retten\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Interview zum Thema Scheidung: Viele wollen noch etwas retten - Praxis f\u00fcr Paartherapie Berlin-Mitte\" \/>\n<meta property=\"og:description\" content=\"Die Scheidungszahlen sinken? Ein Interview, das Frau Wettlaufer-Pohl von der Nordhessischen Allgemeinen, mit mir gef\u00fchrt hat, hier zum Nachlesen: 20170717- Interview-sinkende-Scheidungszahlen (PDF) &nbsp; &nbsp;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/paartherapie-coupletherapy.de\/interview-zum-thema-scheidung-viele-wollen-noch-etwas-retten\/\" \/>\n<meta property=\"og:site_name\" content=\"Praxis f\u00fcr Paartherapie Berlin-Mitte\" \/>\n<meta property=\"article:published_time\" content=\"2017-07-18T10:48:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-09-07T11:17:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/paartherapie-coupletherapy.de\/wp-content\/uploads\/2018\/02\/video.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1604\" \/>\n\t<meta property=\"og:image:height\" content=\"1003\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"jb_admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"jb_admin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/paartherapie-coupletherapy.de\/interview-zum-thema-scheidung-viele-wollen-noch-etwas-retten\/\",\"url\":\"https:\/\/paartherapie-coupletherapy.de\/interview-zum-thema-scheidung-viele-wollen-noch-etwas-retten\/\",\"name\":\"Interview zum Thema Scheidung: Viele wollen noch etwas retten - Praxis f\u00fcr Paartherapie Berlin-Mitte\",\"isPartOf\":{\"@id\":\"https:\/\/paartherapie-coupletherapy.de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/paartherapie-coupletherapy.de\/interview-zum-thema-scheidung-viele-wollen-noch-etwas-retten\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/paartherapie-coupletherapy.de\/interview-zum-thema-scheidung-viele-wollen-noch-etwas-retten\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/paartherapie-coupletherapy.de\/wp-content\/uploads\/2018\/02\/video.jpg\",\"datePublished\":\"2017-07-18T10:48:57+00:00\",\"dateModified\":\"2018-09-07T11:17:30+00:00\",\"author\":{\"@id\":\"https:\/\/paartherapie-coupletherapy.de\/#\/schema\/person\/d19eeeb0a4e4b4e0afd6a2114f4714fd\"},\"breadcrumb\":{\"@id\":\"https:\/\/paartherapie-coupletherapy.de\/interview-zum-thema-scheidung-viele-wollen-noch-etwas-retten\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/paartherapie-coupletherapy.de\/interview-zum-thema-scheidung-viele-wollen-noch-etwas-retten\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/paartherapie-coupletherapy.de\/interview-zum-thema-scheidung-viele-wollen-noch-etwas-retten\/#primaryimage\",\"url\":\"https:\/\/paartherapie-coupletherapy.de\/wp-content\/uploads\/2018\/02\/video.jpg\",\"contentUrl\":\"https:\/\/paartherapie-coupletherapy.de\/wp-content\/uploads\/2018\/02\/video.jpg\",\"width\":1604,\"height\":1003,\"caption\":\"Julia Bellabarba, Paartherapeutin in Berlin\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/paartherapie-coupletherapy.de\/interview-zum-thema-scheidung-viele-wollen-noch-etwas-retten\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/paartherapie-coupletherapy.de\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Interview zum Thema Scheidung: Viele wollen noch etwas retten\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/paartherapie-coupletherapy.de\/#website\",\"url\":\"https:\/\/paartherapie-coupletherapy.de\/\",\"name\":\"Praxis f\u00fcr Paartherapie Berlin-Mitte\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/paartherapie-coupletherapy.de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/paartherapie-coupletherapy.de\/#\/schema\/person\/d19eeeb0a4e4b4e0afd6a2114f4714fd\",\"name\":\"jb_admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/paartherapie-coupletherapy.de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5241d51dbb98e7f9bef6c0f2519c8171795bf96310e32029655e454ca32954dc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5241d51dbb98e7f9bef6c0f2519c8171795bf96310e32029655e454ca32954dc?s=96&d=mm&r=g\",\"caption\":\"jb_admin\"},\"url\":\"https:\/\/paartherapie-coupletherapy.de\/en\/author\/jb_admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Interview zum Thema Scheidung: Viele wollen noch etwas retten - Praxis f\u00fcr Paartherapie Berlin-Mitte","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/paartherapie-coupletherapy.de\/interview-zum-thema-scheidung-viele-wollen-noch-etwas-retten\/","og_locale":"en_US","og_type":"article","og_title":"Interview zum Thema Scheidung: Viele wollen noch etwas retten - Praxis f\u00fcr Paartherapie Berlin-Mitte","og_description":"Die Scheidungszahlen sinken? Ein Interview, das Frau Wettlaufer-Pohl von der Nordhessischen Allgemeinen, mit mir gef\u00fchrt hat, hier zum Nachlesen: 20170717- Interview-sinkende-Scheidungszahlen (PDF) &nbsp; &nbsp;","og_url":"https:\/\/paartherapie-coupletherapy.de\/interview-zum-thema-scheidung-viele-wollen-noch-etwas-retten\/","og_site_name":"Praxis f\u00fcr Paartherapie Berlin-Mitte","article_published_time":"2017-07-18T10:48:57+00:00","article_modified_time":"2018-09-07T11:17:30+00:00","og_image":[{"width":1604,"height":1003,"url":"https:\/\/paartherapie-coupletherapy.de\/wp-content\/uploads\/2018\/02\/video.jpg","type":"image\/jpeg"}],"author":"jb_admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"jb_admin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/paartherapie-coupletherapy.de\/interview-zum-thema-scheidung-viele-wollen-noch-etwas-retten\/","url":"https:\/\/paartherapie-coupletherapy.de\/interview-zum-thema-scheidung-viele-wollen-noch-etwas-retten\/","name":"Interview zum Thema Scheidung: Viele wollen noch etwas retten - Praxis f\u00fcr Paartherapie Berlin-Mitte","isPartOf":{"@id":"https:\/\/paartherapie-coupletherapy.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/paartherapie-coupletherapy.de\/interview-zum-thema-scheidung-viele-wollen-noch-etwas-retten\/#primaryimage"},"image":{"@id":"https:\/\/paartherapie-coupletherapy.de\/interview-zum-thema-scheidung-viele-wollen-noch-etwas-retten\/#primaryimage"},"thumbnailUrl":"https:\/\/paartherapie-coupletherapy.de\/wp-content\/uploads\/2018\/02\/video.jpg","datePublished":"2017-07-18T10:48:57+00:00","dateModified":"2018-09-07T11:17:30+00:00","author":{"@id":"https:\/\/paartherapie-coupletherapy.de\/#\/schema\/person\/d19eeeb0a4e4b4e0afd6a2114f4714fd"},"breadcrumb":{"@id":"https:\/\/paartherapie-coupletherapy.de\/interview-zum-thema-scheidung-viele-wollen-noch-etwas-retten\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/paartherapie-coupletherapy.de\/interview-zum-thema-scheidung-viele-wollen-noch-etwas-retten\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/paartherapie-coupletherapy.de\/interview-zum-thema-scheidung-viele-wollen-noch-etwas-retten\/#primaryimage","url":"https:\/\/paartherapie-coupletherapy.de\/wp-content\/uploads\/2018\/02\/video.jpg","contentUrl":"https:\/\/paartherapie-coupletherapy.de\/wp-content\/uploads\/2018\/02\/video.jpg","width":1604,"height":1003,"caption":"Julia Bellabarba, Paartherapeutin in Berlin"},{"@type":"BreadcrumbList","@id":"https:\/\/paartherapie-coupletherapy.de\/interview-zum-thema-scheidung-viele-wollen-noch-etwas-retten\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/paartherapie-coupletherapy.de\/en\/"},{"@type":"ListItem","position":2,"name":"Interview zum Thema Scheidung: Viele wollen noch etwas retten"}]},{"@type":"WebSite","@id":"https:\/\/paartherapie-coupletherapy.de\/#website","url":"https:\/\/paartherapie-coupletherapy.de\/","name":"Praxis f\u00fcr Paartherapie Berlin-Mitte","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/paartherapie-coupletherapy.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/paartherapie-coupletherapy.de\/#\/schema\/person\/d19eeeb0a4e4b4e0afd6a2114f4714fd","name":"jb_admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/paartherapie-coupletherapy.de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5241d51dbb98e7f9bef6c0f2519c8171795bf96310e32029655e454ca32954dc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5241d51dbb98e7f9bef6c0f2519c8171795bf96310e32029655e454ca32954dc?s=96&d=mm&r=g","caption":"jb_admin"},"url":"https:\/\/paartherapie-coupletherapy.de\/en\/author\/jb_admin\/"}]}},"_links":{"self":[{"href":"https:\/\/paartherapie-coupletherapy.de\/en\/wp-json\/wp\/v2\/posts\/1411","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/paartherapie-coupletherapy.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/paartherapie-coupletherapy.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/paartherapie-coupletherapy.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/paartherapie-coupletherapy.de\/en\/wp-json\/wp\/v2\/comments?post=1411"}],"version-history":[{"count":8,"href":"https:\/\/paartherapie-coupletherapy.de\/en\/wp-json\/wp\/v2\/posts\/1411\/revisions"}],"predecessor-version":[{"id":1728,"href":"https:\/\/paartherapie-coupletherapy.de\/en\/wp-json\/wp\/v2\/posts\/1411\/revisions\/1728"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/paartherapie-coupletherapy.de\/en\/wp-json\/wp\/v2\/media\/1587"}],"wp:attachment":[{"href":"https:\/\/paartherapie-coupletherapy.de\/en\/wp-json\/wp\/v2\/media?parent=1411"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/paartherapie-coupletherapy.de\/en\/wp-json\/wp\/v2\/categories?post=1411"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/paartherapie-coupletherapy.de\/en\/wp-json\/wp\/v2\/tags?post=1411"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}