{"id":2049,"date":"2020-03-23T18:42:02","date_gmt":"2020-03-23T17:42:02","guid":{"rendered":"https:\/\/paartherapie-coupletherapy.de\/?p=2049"},"modified":"2020-04-29T10:30:12","modified_gmt":"2020-04-29T08:30:12","slug":"liebe-in-zeiten-der","status":"publish","type":"post","link":"https:\/\/paartherapie-coupletherapy.de\/en\/liebe-in-zeiten-der\/","title":{"rendered":"Liebe in Zeiten der &#8230;"},"content":{"rendered":"\n<p>Als Unterst\u00fctzung und Anregung (oder einfach nur zur Ablenkung) werde ich in den kommenden Wochen hier regelm\u00e4\u00dfig Texte und Links ver\u00f6ffentlichen, die hoffentlich etwas Ruhe, Zuversicht und Entlastung in Ihren Pandemie- Alltag bringen werden.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Liebe in Zeiten der &#8230; <\/h2>\n\n\n\n<p>Zun\u00e4chst einmal einige aktuelle Informationen, die viele von Ihnen schon bekommen haben.<\/p>\n\n\n\n<p><strong>Ab sofort und bis auf Weiteres werden keine weiteren Termine in der Praxis stattfinden. <\/strong><\/p>\n\n\n\n<p>Niemand\nvon uns wei\u00df zum jetzigen Zeitpunkt, wie sich die Situation hier in Berlin, in\nDeutschland und weltweit entwickeln wird. Und diese Ungewissheit ist f\u00fcr viele\nvon uns besonders schwer zu ertragen.<\/p>\n\n\n\n<p>Ich\nbem\u00fche mich &#8211; so wie die meisten -, realistisch und flexibel zu bleiben.<\/p>\n\n\n\n<p>Da\nwir uns auf l\u00e4ngerfristige Einschr\u00e4nkungen einstellen m\u00fcssen, oder darauf zumindest\nvorbereitet sein sollten, werde ich die n\u00f6tigen Voraussetzungen schaffen, um\nonline Gespr\u00e4che anbieten zu k\u00f6nnen.<\/p>\n\n\n\n<p>Das\nwird aufgrund meines mangelnden technischen Sachverstandes zwar etwas dauern,\naber ich informiere Sie selbstverst\u00e4ndlich umgehend dar\u00fcber, wenn es soweit\nist. Und Sie k\u00f6nnen diese Option dann in Anspruch nehmen, wenn es f\u00fcr Sie\npasst.<\/p>\n\n\n\n<p>Zuversicht,\nHumor und Liebe helfen jetzt besonders.<\/p>\n\n\n\n<p>Ihre\nJulia Bellabarba&nbsp;<\/p>\n\n\n\n<p>Spread\nlove \u2764\ufe0f not germs \ud83e\udda0<\/p>\n\n\n\n<p><br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Als Unterst\u00fctzung und Anregung (oder einfach nur zur Ablenkung) werde ich in den kommenden Wochen hier regelm\u00e4\u00dfig Texte und Links ver\u00f6ffentlichen, die hoffentlich etwas Ruhe, Zuversicht<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":2,"featured_media":2057,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-2049","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-krisenzeit"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Liebe in Zeiten der ... - Praxis f\u00fcr Paartherapie Berlin-Mitte<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/paartherapie-coupletherapy.de\/liebe-in-zeiten-der\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Liebe in Zeiten der ... - Praxis f\u00fcr Paartherapie Berlin-Mitte\" \/>\n<meta property=\"og:description\" content=\"Als Unterst\u00fctzung und Anregung (oder einfach nur zur Ablenkung) werde ich in den kommenden Wochen hier regelm\u00e4\u00dfig Texte und Links ver\u00f6ffentlichen, die hoffentlich etwas Ruhe, Zuversicht [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/paartherapie-coupletherapy.de\/liebe-in-zeiten-der\/\" \/>\n<meta property=\"og:site_name\" content=\"Praxis f\u00fcr Paartherapie Berlin-Mitte\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-23T17:42:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-29T08:30:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/paartherapie-coupletherapy.de\/wp-content\/uploads\/2020\/03\/feldmann_paartherapie-700x280.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Julia Bellabarba\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Julia Bellabarba\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/paartherapie-coupletherapy.de\/liebe-in-zeiten-der\/\",\"url\":\"https:\/\/paartherapie-coupletherapy.de\/liebe-in-zeiten-der\/\",\"name\":\"Liebe in Zeiten der ... - Praxis f\u00fcr Paartherapie Berlin-Mitte\",\"isPartOf\":{\"@id\":\"https:\/\/paartherapie-coupletherapy.de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/paartherapie-coupletherapy.de\/liebe-in-zeiten-der\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/paartherapie-coupletherapy.de\/liebe-in-zeiten-der\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/paartherapie-coupletherapy.de\/wp-content\/uploads\/2020\/03\/feldmann_paartherapie-700x280.jpg\",\"datePublished\":\"2020-03-23T17:42:02+00:00\",\"dateModified\":\"2020-04-29T08:30:12+00:00\",\"author\":{\"@id\":\"https:\/\/paartherapie-coupletherapy.de\/#\/schema\/person\/feaec33cc2479c53caf5cfeffd4bccb0\"},\"breadcrumb\":{\"@id\":\"https:\/\/paartherapie-coupletherapy.de\/liebe-in-zeiten-der\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/paartherapie-coupletherapy.de\/liebe-in-zeiten-der\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/paartherapie-coupletherapy.de\/liebe-in-zeiten-der\/#primaryimage\",\"url\":\"https:\/\/paartherapie-coupletherapy.de\/wp-content\/uploads\/2020\/03\/feldmann_paartherapie-700x280.jpg\",\"contentUrl\":\"https:\/\/paartherapie-coupletherapy.de\/wp-content\/uploads\/2020\/03\/feldmann_paartherapie-700x280.jpg\",\"width\":700,\"height\":280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/paartherapie-coupletherapy.de\/liebe-in-zeiten-der\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/paartherapie-coupletherapy.de\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Liebe in Zeiten der &#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/paartherapie-coupletherapy.de\/#website\",\"url\":\"https:\/\/paartherapie-coupletherapy.de\/\",\"name\":\"Praxis f\u00fcr Paartherapie Berlin-Mitte\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/paartherapie-coupletherapy.de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/paartherapie-coupletherapy.de\/#\/schema\/person\/feaec33cc2479c53caf5cfeffd4bccb0\",\"name\":\"Julia Bellabarba\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/paartherapie-coupletherapy.de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/230c5f20075f1ee23ffc6ecb25586d834a8076bcbc3def1274d5c0ce41d3f8f7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/230c5f20075f1ee23ffc6ecb25586d834a8076bcbc3def1274d5c0ce41d3f8f7?s=96&d=mm&r=g\",\"caption\":\"Julia Bellabarba\"},\"url\":\"https:\/\/paartherapie-coupletherapy.de\/en\/author\/jbella\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Liebe in Zeiten der ... - Praxis f\u00fcr Paartherapie Berlin-Mitte","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/paartherapie-coupletherapy.de\/liebe-in-zeiten-der\/","og_locale":"en_US","og_type":"article","og_title":"Liebe in Zeiten der ... - Praxis f\u00fcr Paartherapie Berlin-Mitte","og_description":"Als Unterst\u00fctzung und Anregung (oder einfach nur zur Ablenkung) werde ich in den kommenden Wochen hier regelm\u00e4\u00dfig Texte und Links ver\u00f6ffentlichen, die hoffentlich etwas Ruhe, Zuversicht [\u2026]","og_url":"https:\/\/paartherapie-coupletherapy.de\/liebe-in-zeiten-der\/","og_site_name":"Praxis f\u00fcr Paartherapie Berlin-Mitte","article_published_time":"2020-03-23T17:42:02+00:00","article_modified_time":"2020-04-29T08:30:12+00:00","og_image":[{"width":700,"height":280,"url":"https:\/\/paartherapie-coupletherapy.de\/wp-content\/uploads\/2020\/03\/feldmann_paartherapie-700x280.jpg","type":"image\/jpeg"}],"author":"Julia Bellabarba","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Julia Bellabarba","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/paartherapie-coupletherapy.de\/liebe-in-zeiten-der\/","url":"https:\/\/paartherapie-coupletherapy.de\/liebe-in-zeiten-der\/","name":"Liebe in Zeiten der ... - Praxis f\u00fcr Paartherapie Berlin-Mitte","isPartOf":{"@id":"https:\/\/paartherapie-coupletherapy.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/paartherapie-coupletherapy.de\/liebe-in-zeiten-der\/#primaryimage"},"image":{"@id":"https:\/\/paartherapie-coupletherapy.de\/liebe-in-zeiten-der\/#primaryimage"},"thumbnailUrl":"https:\/\/paartherapie-coupletherapy.de\/wp-content\/uploads\/2020\/03\/feldmann_paartherapie-700x280.jpg","datePublished":"2020-03-23T17:42:02+00:00","dateModified":"2020-04-29T08:30:12+00:00","author":{"@id":"https:\/\/paartherapie-coupletherapy.de\/#\/schema\/person\/feaec33cc2479c53caf5cfeffd4bccb0"},"breadcrumb":{"@id":"https:\/\/paartherapie-coupletherapy.de\/liebe-in-zeiten-der\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/paartherapie-coupletherapy.de\/liebe-in-zeiten-der\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/paartherapie-coupletherapy.de\/liebe-in-zeiten-der\/#primaryimage","url":"https:\/\/paartherapie-coupletherapy.de\/wp-content\/uploads\/2020\/03\/feldmann_paartherapie-700x280.jpg","contentUrl":"https:\/\/paartherapie-coupletherapy.de\/wp-content\/uploads\/2020\/03\/feldmann_paartherapie-700x280.jpg","width":700,"height":280},{"@type":"BreadcrumbList","@id":"https:\/\/paartherapie-coupletherapy.de\/liebe-in-zeiten-der\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/paartherapie-coupletherapy.de\/en\/"},{"@type":"ListItem","position":2,"name":"Liebe in Zeiten der &#8230;"}]},{"@type":"WebSite","@id":"https:\/\/paartherapie-coupletherapy.de\/#website","url":"https:\/\/paartherapie-coupletherapy.de\/","name":"Praxis f\u00fcr Paartherapie Berlin-Mitte","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/paartherapie-coupletherapy.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/paartherapie-coupletherapy.de\/#\/schema\/person\/feaec33cc2479c53caf5cfeffd4bccb0","name":"Julia Bellabarba","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/paartherapie-coupletherapy.de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/230c5f20075f1ee23ffc6ecb25586d834a8076bcbc3def1274d5c0ce41d3f8f7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/230c5f20075f1ee23ffc6ecb25586d834a8076bcbc3def1274d5c0ce41d3f8f7?s=96&d=mm&r=g","caption":"Julia Bellabarba"},"url":"https:\/\/paartherapie-coupletherapy.de\/en\/author\/jbella\/"}]}},"_links":{"self":[{"href":"https:\/\/paartherapie-coupletherapy.de\/en\/wp-json\/wp\/v2\/posts\/2049","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/paartherapie-coupletherapy.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/paartherapie-coupletherapy.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/paartherapie-coupletherapy.de\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/paartherapie-coupletherapy.de\/en\/wp-json\/wp\/v2\/comments?post=2049"}],"version-history":[{"count":5,"href":"https:\/\/paartherapie-coupletherapy.de\/en\/wp-json\/wp\/v2\/posts\/2049\/revisions"}],"predecessor-version":[{"id":2054,"href":"https:\/\/paartherapie-coupletherapy.de\/en\/wp-json\/wp\/v2\/posts\/2049\/revisions\/2054"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/paartherapie-coupletherapy.de\/en\/wp-json\/wp\/v2\/media\/2057"}],"wp:attachment":[{"href":"https:\/\/paartherapie-coupletherapy.de\/en\/wp-json\/wp\/v2\/media?parent=2049"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/paartherapie-coupletherapy.de\/en\/wp-json\/wp\/v2\/categories?post=2049"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/paartherapie-coupletherapy.de\/en\/wp-json\/wp\/v2\/tags?post=2049"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}